{"id":1313,"date":"2022-09-01T14:54:19","date_gmt":"2022-09-01T19:54:19","guid":{"rendered":"https:\/\/azzorti.com\/bo\/?page_id=1313"},"modified":"2025-05-05T15:55:34","modified_gmt":"2025-05-05T20:55:34","slug":"terminos-y-condiciones","status":"publish","type":"page","link":"https:\/\/azzorti.com\/bo\/terminos-y-condiciones\/","title":{"rendered":"T\u00e9rminos y Condiciones"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1313\" class=\"elementor elementor-1313\" data-elementor-settings=\"[]\">\n\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t<section class=\"elementor-element elementor-element-907a40f elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-section elementor-top-section\" data-id=\"907a40f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b9644e elementor-column elementor-col-100 elementor-top-column\" data-id=\"7b9644e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap  elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t<div class=\"elementor-element elementor-element-82f564c elementor-nav-menu--indicator-classic elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"82f564c\" data-element_type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<nav role=\"navigation\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-underline e--animation-fade\"><ul id=\"menu-1-82f564c\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-2107\"><a target=\"_blank\" href=\"https:\/\/pluton.azzorti.bo\/\" class=\"elementor-item menu-link\">Aula Virtual<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-2866\"><a href=\"https:\/\/neptuno.azzorti.com\/inicio\/\" class=\"elementor-item menu-link\">Neptuno<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-2109\"><a target=\"_blank\" href=\"https:\/\/alcor.azzorti.bo\/portal_pagos\/portal_pagos.html\" class=\"elementor-item menu-link\">Paga Aqu\u00ed<\/a><\/li>\n<\/ul><\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i class=\"eicon-menu-bar\" aria-hidden=\"true\"><\/i>\n\t\t\t<span class=\"elementor-screen-only\">Menu<\/span>\n\t\t<\/div>\n\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" role=\"navigation\" aria-hidden=\"true\"><ul id=\"menu-2-82f564c\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-2107\"><a target=\"_blank\" href=\"https:\/\/pluton.azzorti.bo\/\" class=\"elementor-item menu-link\">Aula Virtual<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-2866\"><a href=\"https:\/\/neptuno.azzorti.com\/inicio\/\" class=\"elementor-item menu-link\">Neptuno<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-2109\"><a target=\"_blank\" href=\"https:\/\/alcor.azzorti.bo\/portal_pagos\/portal_pagos.html\" class=\"elementor-item menu-link\">Paga Aqu\u00ed<\/a><\/li>\n<\/ul><\/nav>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-element elementor-element-8575ca3 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-section elementor-top-section\" data-id=\"8575ca3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3935b69 elementor-column elementor-col-33 elementor-top-column\" data-id=\"3935b69\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap  elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c5acf6 elementor-widget elementor-widget-image\" data-id=\"2c5acf6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/ec\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"186\" height=\"31\" src=\"https:\/\/azzorti.com\/bo\/wp-content\/uploads\/sites\/11\/2022\/08\/logo-1.jpg\" class=\"attachment-large size-large\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa575a5 elementor-column elementor-col-33 elementor-top-column\" data-id=\"aa575a5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap  elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t<div class=\"elementor-element elementor-element-befca3b elementor-nav-menu__align-center elementor-nav-menu--indicator-classic elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"befca3b\" data-element_type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<nav role=\"navigation\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-underline e--animation-fade\"><ul id=\"menu-1-befca3b\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-239\"><a href=\"https:\/\/azzorti.com\/bo\/\" class=\"elementor-item menu-link\">Inicio<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-246\"><a href=\"https:\/\/azzorti.com\/bo\/catalogos\/\" class=\"elementor-item menu-link\">Cat\u00e1logos<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-3190\"><a href=\"https:\/\/alcor.azzorti.bo\/vinculacion\/\" class=\"elementor-item menu-link\">Quiero ser Asesora<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1205\"><a href=\"https:\/\/azzorti.com\/bo\/contacta-asesora\/\" class=\"elementor-item menu-link\">Contacta una Asesora<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-2108\"><a href=\"https:\/\/intranet.azzorti.bo\/\" class=\"elementor-item menu-link\">Intranet<\/a><\/li>\n<\/ul><\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i class=\"eicon-menu-bar\" aria-hidden=\"true\"><\/i>\n\t\t\t<span class=\"elementor-screen-only\">Menu<\/span>\n\t\t<\/div>\n\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" role=\"navigation\" aria-hidden=\"true\"><ul id=\"menu-2-befca3b\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-239\"><a href=\"https:\/\/azzorti.com\/bo\/\" class=\"elementor-item menu-link\">Inicio<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-246\"><a href=\"https:\/\/azzorti.com\/bo\/catalogos\/\" class=\"elementor-item menu-link\">Cat\u00e1logos<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-3190\"><a href=\"https:\/\/alcor.azzorti.bo\/vinculacion\/\" class=\"elementor-item menu-link\">Quiero ser Asesora<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1205\"><a href=\"https:\/\/azzorti.com\/bo\/contacta-asesora\/\" class=\"elementor-item menu-link\">Contacta una Asesora<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-2108\"><a href=\"https:\/\/intranet.azzorti.bo\/\" class=\"elementor-item menu-link\">Intranet<\/a><\/li>\n<\/ul><\/nav>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c313d90 elementor-column elementor-col-33 elementor-top-column\" data-id=\"c313d90\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap  elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t<div class=\"elementor-element elementor-element-84c7daf elementor-widget elementor-widget-text-editor\" data-id=\"84c7daf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\"><div class=\"lgn_usua\"><a href=\"https:\/\/pedidos.azzorti.bo\/\">\n<img decoding=\"async\" src=\"https:\/\/azzorti.com\/bo\/wp-content\/uploads\/sites\/3\/2022\/08\/usuario.jpg\" align=\"left\" \/><b class=\"login\">SOY ASESORA<\/b><\/a>\n<button class=\"btn-login\" type=\"button\"><a href=\"https:\/\/pedidos.azzorti.bo\/\">INGRESAR<\/a><\/button><\/div><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-element elementor-element-200423c elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-section elementor-top-section\" data-id=\"200423c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8cd419c elementor-column elementor-col-100 elementor-top-column\" data-id=\"8cd419c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap  elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d28f8fe elementor-widget elementor-widget-shortcode\" data-id=\"d28f8fe\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div class=\"breadcrumbs-anywhere\">\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62f3394 elementor-widget elementor-widget-spacer\" data-id=\"62f3394\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-element elementor-element-bd2bd30 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-section elementor-top-section\" data-id=\"bd2bd30\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4837217 elementor-column elementor-col-100 elementor-top-column\" data-id=\"4837217\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap  elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t<div class=\"elementor-element elementor-element-140cc6f elementor-widget elementor-widget-image\" data-id=\"140cc6f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"267\" src=\"https:\/\/azzorti.com\/bo\/wp-content\/uploads\/sites\/11\/2022\/08\/6hwz5qhzwey7eggjqnwztp-1024x267.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/azzorti.com\/bo\/wp-content\/uploads\/sites\/11\/2022\/08\/6hwz5qhzwey7eggjqnwztp-1024x267.jpg 1024w, https:\/\/azzorti.com\/bo\/wp-content\/uploads\/sites\/11\/2022\/08\/6hwz5qhzwey7eggjqnwztp-300x78.jpg 300w, https:\/\/azzorti.com\/bo\/wp-content\/uploads\/sites\/11\/2022\/08\/6hwz5qhzwey7eggjqnwztp-768x200.jpg 768w, https:\/\/azzorti.com\/bo\/wp-content\/uploads\/sites\/11\/2022\/08\/6hwz5qhzwey7eggjqnwztp-1536x400.jpg 1536w, https:\/\/azzorti.com\/bo\/wp-content\/uploads\/sites\/11\/2022\/08\/6hwz5qhzwey7eggjqnwztp-2048x534.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6cabcf1 elementor-widget elementor-widget-text-editor\" data-id=\"6cabcf1\" data-element_type=\"widget\" id=\"politica_ases_title\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\"><h1 class=\"main-title axc-mb-12 md:axc-mb-15\">T\u00e9rminos y Condiciones<\/h1><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-element elementor-element-313d50a elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-section elementor-top-section\" data-id=\"313d50a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cfce0e3 elementor-column elementor-col-66 elementor-top-column\" data-id=\"cfce0e3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap  elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9a6ccbf elementor-widget elementor-widget-text-editor\" data-id=\"9a6ccbf\" data-element_type=\"widget\" id=\"article_terminos\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\"><h3>T\u00e9rminos y Condiciones<\/h3><p>Apreciada Asesora:<\/p><p><strong>Confidencialidad:<\/strong> Recuerde que usted ser\u00e1 la \u00fanica responsable de los productos que solicite por este medio y para garantizarlo se le ha suministrado una clave que podr\u00e1 cambiar en el momento que ingrese, de manera que pueda mantener la absoluta confidencialidad.<\/p><p><strong>Validaci\u00f3n del pedido:<\/strong> Una vez realizada la compra y cerrado el pedido por parte suya, entra en un proceso de validaci\u00f3n para verificar si cumple con las normas, pol\u00edticas y condiciones comerciales establecidas. Si por alg\u00fan motivo su pedido no es procesado, nos comunicaremos para informarle. Por tal raz\u00f3n es importante que actualice sus n\u00fameros de contacto y correo electr\u00f3nico.<\/p><p>\u00a0<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d3f746f elementor-widget elementor-widget-wp-widget-custom_html\" data-id=\"d3f746f\" data-element_type=\"widget\" data-widget_type=\"wp-widget-custom_html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"textwidget custom-html-widget\"><a class=\"axc-btn\" href=\"\/bo\/politica-de-tratamiento-de-datos\/\" target=\"_blank\">T\u00c9RMINOS Y CONDICIONES<\/a><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8bb1fcd elementor-column elementor-col-33 elementor-top-column\" data-id=\"8bb1fcd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-element elementor-element-65ef639 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-section elementor-top-section\" data-id=\"65ef639\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2e92831 elementor-column elementor-col-100 elementor-top-column\" data-id=\"2e92831\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap  elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c27f7f3 elementor-widget elementor-widget-divider\" data-id=\"c27f7f3\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-element elementor-element-f779e96 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-section elementor-top-section\" data-id=\"f779e96\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b00786f elementor-column elementor-col-100 elementor-top-column\" data-id=\"b00786f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap  elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e8010f9 elementor-widget elementor-widget-divider\" data-id=\"e8010f9\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-element elementor-element-adb469b elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-section elementor-top-section\" data-id=\"adb469b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b338fb6 elementor-column elementor-col-100 elementor-top-column\" data-id=\"b338fb6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap  elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t<div class=\"elementor-element elementor-element-201e186 elementor-widget elementor-widget-image\" data-id=\"201e186\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"186\" height=\"31\" src=\"https:\/\/azzorti.com\/bo\/wp-content\/uploads\/sites\/11\/2022\/08\/logo-1.jpg\" class=\"attachment-large size-large\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-element elementor-element-524021c elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-section elementor-top-section\" data-id=\"524021c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t<div class=\"elementor-element elementor-element-47ea618 elementor-column elementor-col-33 elementor-top-column\" data-id=\"47ea618\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap  elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0e20a66 elementor-widget elementor-widget-text-editor\" data-id=\"0e20a66\" data-element_type=\"widget\" id=\"footer\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\"><p>Respaldamos el crecimiento integral de la mujer, nos apasiona la realizaci\u00f3n de sus sue\u00f1os, la mejora de su nivel de vida y el de su familia. Nuestro prop\u00f3sito es que m\u00e1s mujeres apuesten por ellas mismas.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07d4ebe elementor-shape-circle elementor-widget elementor-widget-social-icons\" data-id=\"07d4ebe\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-social-icons-wrapper\">\n\t\t\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook-f elementor-repeater-item-c706ebe\" href=\"https:\/\/www.facebook.com\/Azzorti.Bol\" target=\"_blank\">\n\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook-f<\/span>\n\t\t\t\t\t<i class=\"fab fa-facebook-f\"><\/i>\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-fa3579d\" href=\"https:\/\/instagram.com\/azzorti.oficial?igshid=OGQ5ZDc2ODk2ZA==\" target=\"_blank\">\n\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t<i class=\"fab fa-instagram\"><\/i>\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-youtube elementor-repeater-item-6c2ac9c\" href=\"https:\/\/www.youtube.com\/channel\/UCWifzVYUH34BkGdTIBG6Bmg\" target=\"_blank\">\n\t\t\t\t\t<span class=\"elementor-screen-only\">Youtube<\/span>\n\t\t\t\t\t<i class=\"fab fa-youtube\"><\/i>\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-linkedin elementor-repeater-item-8452732\" href=\"https:\/\/co.linkedin.com\/company\/azzortilatam\" target=\"_blank\">\n\t\t\t\t\t<span class=\"elementor-screen-only\">Linkedin<\/span>\n\t\t\t\t\t<i class=\"fab fa-linkedin\"><\/i>\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16c4665 elementor-column elementor-col-33 elementor-top-column\" data-id=\"16c4665\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap  elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bded50b elementor-widget elementor-widget-text-editor\" data-id=\"bded50b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\"><p>Direcci\u00f3n:<\/p><p>Parque Industrial, Manzano 29B, Lote 1.<br \/>Santa Cruz \u2013 Bolivia<\/p><p>Contacto:<br \/>L\u00ednea atenci\u00f3n : 318\u20130015<br \/>WhatsApp Serena : <b style=\"caret-color: #212121; color: #212121; font-family: Aptos, sans-serif; font-size: 14.666667px; font-style: normal; font-variant-caps: normal; letter-spacing: normal; orphans: auto; text-align: start; text-indent: 0px; text-transform: none; white-space: normal; widows: auto; word-spacing: 0px; -webkit-text-stroke-width: 0px; text-decoration: none;\"><span style=\"font-size: 12pt; font-family: Gilroy; line-height: 1.2;\"><span style=\"color: inherit !important; background-color: inherit !important;\"><span style=\"color: inherit !important; background-color: inherit !important;\"><a style=\"color: #0078d7;\" href=\"https:\/\/api.whatsapp.com\/send?phone=59177681604\">+591 77681604<\/a><\/span><\/span><\/span><\/b><span style=\"caret-color: #212121; color: #212121; font-size: 14.666667px; font-style: normal; font-variant-caps: normal; font-weight: 400; letter-spacing: normal; orphans: auto; text-align: start; text-indent: 0px; text-transform: none; white-space: normal; widows: auto; word-spacing: 0px; -webkit-text-stroke-width: 0px; text-decoration: none; font-family: Gilroy;\"><span class=\"Apple-converted-space\"> <br \/><\/span><\/span><\/p><p>Email:<\/p><p>servicioalcliente.bolivia@azzorti.bo<\/p><p>Horario de atenci\u00f3n:<br \/>Lunes a viernes 8:00 a.m a 6:00 p.m.<br \/>S\u00e1bado 8:00 a.m a 12:00 p.m.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d05dd8 elementor-column elementor-col-33 elementor-top-column\" data-id=\"0d05dd8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap  elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7f2fbfb elementor-widget elementor-widget-text-editor\" data-id=\"7f2fbfb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\"><p><a href=\"https:\/\/azzorti.com\/bo\/mision-y-vision\/\" target=\"_blank\" rel=\"noopener\">Misi\u00f3n y Visi\u00f3n<\/a><\/p><p>\u00a0<\/p><p><a href=\"\/bo\/contacto\">Contacto<\/a><br \/><br \/><a href=\"\/bo\/preguntas-frecuentes\/\">Preguntas frecuentes<\/a><br \/><br \/><a href=\"\/bo\/quienes-somos\">Qui\u00e9nes somos<\/a><br \/><br \/><a href=\"https:\/\/intranet.azzorti.bo\/desarrollo\/cgis\/\">Intranet<\/a><br \/><br \/><a href=\"\/bo\/politicas-asesoras-independientes\/\">Pol\u00edtica Asesoras independiente AZZORTI<\/a><br \/><br \/><a href=\"\/bo\/politica-de-tratamiento-de-datos\/\">Pol\u00edtica de Privacidad<\/a><br \/><br \/><a href=\"\/bo\/politica-de-cambios-y-devoluciones\/\">Pol\u00edtica de Cambios y Devoluciones<\/a><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-element elementor-element-5dea54b elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-section elementor-top-section\" data-id=\"5dea54b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7421d05 elementor-column elementor-col-100 elementor-top-column\" data-id=\"7421d05\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap  elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4efcafb elementor-widget elementor-widget-image\" data-id=\"4efcafb\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"186\" height=\"31\" src=\"https:\/\/azzorti.com\/bo\/wp-content\/uploads\/sites\/11\/2022\/08\/logo-1.jpg\" class=\"attachment-large size-large\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-element elementor-element-5c1041c elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-section elementor-top-section\" data-id=\"5c1041c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4d53bca elementor-column elementor-col-100 elementor-top-column\" data-id=\"4d53bca\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap  elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d2c5659 elementor-widget elementor-widget-text-editor\" data-id=\"d2c5659\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\"><p>Copyright \u00a9 AZZORTI<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-element elementor-element-d5269dd elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-section elementor-top-section\" data-id=\"d5269dd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e33b026 elementor-column elementor-col-100 elementor-top-column\" data-id=\"e33b026\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap  elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dd448c6 elementor-widget elementor-widget-html\" data-id=\"dd448c6\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<script src=\"https:\/\/alcor2bol.azzorti.com\/bot_pagina\/bot_dupree.js\"><\/script>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2d8b6b9 elementor-widget elementor-widget-html\" data-id=\"2d8b6b9\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>SOY ASESORA INGRESAR T\u00e9rminos y Condiciones T\u00e9rminos y Condiciones Apreciada Asesora: Confidencialidad: Recuerde que usted ser\u00e1 la \u00fanica responsable de los productos que solicite por este medio y para garantizarlo se le ha suministrado una clave que podr\u00e1 cambiar en el momento que ingrese, de manera que pueda mantener la absoluta confidencialidad. Validaci\u00f3n del pedido: &hellip;<\/p>\n<p class=\"read-more\"> <a class=\"\" href=\"https:\/\/azzorti.com\/bo\/terminos-y-condiciones\/\"> <span class=\"screen-reader-text\">T\u00e9rminos y Condiciones<\/span> Leer m\u00e1s &raquo;<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","footnotes":""},"class_list":["post-1313","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>T\u00e9rminos y Condiciones - Azzorti Bolivia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/azzorti.com\/bo\/terminos-y-condiciones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"T\u00e9rminos y Condiciones - Azzorti Bolivia\" \/>\n<meta property=\"og:description\" content=\"SOY ASESORA INGRESAR T\u00e9rminos y Condiciones T\u00e9rminos y Condiciones Apreciada Asesora: Confidencialidad: Recuerde que usted ser\u00e1 la \u00fanica responsable de los productos que solicite por este medio y para garantizarlo se le ha suministrado una clave que podr\u00e1 cambiar en el momento que ingrese, de manera que pueda mantener la absoluta confidencialidad. Validaci\u00f3n del pedido: &hellip; T\u00e9rminos y Condiciones Leer m\u00e1s &raquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/azzorti.com\/bo\/terminos-y-condiciones\/\" \/>\n<meta property=\"og:site_name\" content=\"Azzorti Bolivia\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-05T20:55:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/azzorti.com\/bo\/wp-content\/uploads\/sites\/11\/2022\/08\/logo-1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/azzorti.com\\\/bo\\\/terminos-y-condiciones\\\/\",\"url\":\"https:\\\/\\\/azzorti.com\\\/bo\\\/terminos-y-condiciones\\\/\",\"name\":\"T\u00e9rminos y Condiciones - Azzorti Bolivia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/azzorti.com\\\/bo\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/azzorti.com\\\/bo\\\/terminos-y-condiciones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/azzorti.com\\\/bo\\\/terminos-y-condiciones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/azzorti.com\\\/bo\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2022\\\/08\\\/logo-1.jpg\",\"datePublished\":\"2022-09-01T19:54:19+00:00\",\"dateModified\":\"2025-05-05T20:55:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/azzorti.com\\\/bo\\\/terminos-y-condiciones\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/azzorti.com\\\/bo\\\/terminos-y-condiciones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/azzorti.com\\\/bo\\\/terminos-y-condiciones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/azzorti.com\\\/bo\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2022\\\/08\\\/logo-1.jpg\",\"contentUrl\":\"https:\\\/\\\/azzorti.com\\\/bo\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2022\\\/08\\\/logo-1.jpg\",\"width\":186,\"height\":31},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/azzorti.com\\\/bo\\\/terminos-y-condiciones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/azzorti.com\\\/bo\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"T\u00e9rminos y Condiciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/azzorti.com\\\/bo\\\/#website\",\"url\":\"https:\\\/\\\/azzorti.com\\\/bo\\\/\",\"name\":\"Azzorti Bolivia\",\"description\":\"Azzorti Bolivia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/azzorti.com\\\/bo\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"T\u00e9rminos y Condiciones - Azzorti Bolivia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/azzorti.com\/bo\/terminos-y-condiciones\/","og_locale":"es_ES","og_type":"article","og_title":"T\u00e9rminos y Condiciones - Azzorti Bolivia","og_description":"SOY ASESORA INGRESAR T\u00e9rminos y Condiciones T\u00e9rminos y Condiciones Apreciada Asesora: Confidencialidad: Recuerde que usted ser\u00e1 la \u00fanica responsable de los productos que solicite por este medio y para garantizarlo se le ha suministrado una clave que podr\u00e1 cambiar en el momento que ingrese, de manera que pueda mantener la absoluta confidencialidad. Validaci\u00f3n del pedido: &hellip; T\u00e9rminos y Condiciones Leer m\u00e1s &raquo;","og_url":"https:\/\/azzorti.com\/bo\/terminos-y-condiciones\/","og_site_name":"Azzorti Bolivia","article_modified_time":"2025-05-05T20:55:34+00:00","og_image":[{"url":"https:\/\/azzorti.com\/bo\/wp-content\/uploads\/sites\/11\/2022\/08\/logo-1.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/azzorti.com\/bo\/terminos-y-condiciones\/","url":"https:\/\/azzorti.com\/bo\/terminos-y-condiciones\/","name":"T\u00e9rminos y Condiciones - Azzorti Bolivia","isPartOf":{"@id":"https:\/\/azzorti.com\/bo\/#website"},"primaryImageOfPage":{"@id":"https:\/\/azzorti.com\/bo\/terminos-y-condiciones\/#primaryimage"},"image":{"@id":"https:\/\/azzorti.com\/bo\/terminos-y-condiciones\/#primaryimage"},"thumbnailUrl":"https:\/\/azzorti.com\/bo\/wp-content\/uploads\/sites\/11\/2022\/08\/logo-1.jpg","datePublished":"2022-09-01T19:54:19+00:00","dateModified":"2025-05-05T20:55:34+00:00","breadcrumb":{"@id":"https:\/\/azzorti.com\/bo\/terminos-y-condiciones\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/azzorti.com\/bo\/terminos-y-condiciones\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/azzorti.com\/bo\/terminos-y-condiciones\/#primaryimage","url":"https:\/\/azzorti.com\/bo\/wp-content\/uploads\/sites\/11\/2022\/08\/logo-1.jpg","contentUrl":"https:\/\/azzorti.com\/bo\/wp-content\/uploads\/sites\/11\/2022\/08\/logo-1.jpg","width":186,"height":31},{"@type":"BreadcrumbList","@id":"https:\/\/azzorti.com\/bo\/terminos-y-condiciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/azzorti.com\/bo\/"},{"@type":"ListItem","position":2,"name":"T\u00e9rminos y Condiciones"}]},{"@type":"WebSite","@id":"https:\/\/azzorti.com\/bo\/#website","url":"https:\/\/azzorti.com\/bo\/","name":"Azzorti Bolivia","description":"Azzorti Bolivia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/azzorti.com\/bo\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"}]}},"_links":{"self":[{"href":"https:\/\/azzorti.com\/bo\/wp-json\/wp\/v2\/pages\/1313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/azzorti.com\/bo\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/azzorti.com\/bo\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/azzorti.com\/bo\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/azzorti.com\/bo\/wp-json\/wp\/v2\/comments?post=1313"}],"version-history":[{"count":47,"href":"https:\/\/azzorti.com\/bo\/wp-json\/wp\/v2\/pages\/1313\/revisions"}],"predecessor-version":[{"id":3054,"href":"https:\/\/azzorti.com\/bo\/wp-json\/wp\/v2\/pages\/1313\/revisions\/3054"}],"wp:attachment":[{"href":"https:\/\/azzorti.com\/bo\/wp-json\/wp\/v2\/media?parent=1313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}